{"id":842,"date":"2025-07-14T15:48:34","date_gmt":"2025-07-14T15:48:34","guid":{"rendered":"https:\/\/jolie-pharma.com\/home\/"},"modified":"2026-03-03T15:31:40","modified_gmt":"2026-03-03T13:31:40","slug":"home","status":"publish","type":"page","link":"https:\/\/jolie-pharma.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer uag-hide-tab uag-hide-mob\"><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-desktop uagb-block-fa3d6b73 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<\/div><\/div>\n\n\n\n<div data-aos= \"fade\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-tab uag-hide-mob uagb-block-91492482 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-mob uagb-block-8887bb87 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 20px; font-weight: 100; display: inline-block; letter-spacing: -1.0px;\">\n    POWERED BY\n  <\/span><br>\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 600; display: inline-block; letter-spacing: -3.0px; color: #c29a31;\">\n   \u2b50 102 YEARS OF EXPERIENCE \u2b50\n  <\/span>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-35ee5983 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 20px; font-weight: 100; display: inline-block; letter-spacing: -1.0px;\">\n    POWERED BY\n  <\/span><br>\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 22px; font-weight: 600; display: inline-block; letter-spacing: -3.0px; color: #c29a31;\">\n   \u2b50 102 YEARS OF EXPERIENCE \u2b50\n  <\/span>\n<\/div>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" style=\"margin-top:1px;margin-bottom:1px\"\/>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-07fe63ab alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 500; display: inline-block; letter-spacing: -2.0px;\">\n    TRENDING\n  <\/span><br>\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 25px; font-weight: 100; display: inline-block; letter-spacing: -2.0px;\">\n    PRODUCTS <span style=\"color: #FFD700;\">\ud83d\udd25<\/span>\n  <\/span>\n<\/div>\n\n\n<style id=\"sp_product_slider_dynamic_css2866\">#wps-slider-section #sp-woo-product-slider-2866.wps-product-section .wpsp-pagination-dot .swiper-pagination-bullet{ background-color:#cccccc; } #wps-slider-section #sp-woo-product-slider-2866.wps-product-section .wpsp-pagination-dot .swiper-pagination-bullet.swiper-pagination-bullet-active{ background-color:#333333; }@media (max-width: 480px) {#wps-slider-section #sp-woo-product-slider-2866.wps-product-section .wpsp-pagination-dot { display:none;}}#wps-slider-section #sp-woo-product-slider-2866.wps-product-section[data-layout=grid] { margin-left: -20px;}#wps-slider-section #sp-woo-product-slider-2866 .wpsf-grid-item { padding-left: 20px; margin-bottom: 20px;}#wps-slider-section #sp-woo-product-slider-2866 .wpsf-product-title a{ color: #444444; font-size: 15px; } #wps-slider-section #sp-woo-product-slider-2866 .wpsf-product-title a:hover{ color: #955b89; }#wps-slider-section #sp-woo-product-slider-2866 .wpsf-product-price { color: #222222; font-size: 14px; } #wps-slider-section #sp-woo-product-slider-2866 .wpsf-product-price del span { color: #888888; }#wps-slider-section #sp-woo-product-slider-2866 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button){ color: #ffffff; background-color: #c29a31; border: 0px solid #ffffff; } #wps-slider-section #sp-woo-product-slider-2866 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button):hover, #wps-slider-section #sp-woo-product-slider-2866 .wpsf-cart-button a.added_to_cart{ color: #000000; background-color: #ffffff; border-color: #ffffff; }#sp-woo-product-slider-2866.sp-wps-custom-template .wps-product-image .wpsf-product-img,#sp-woo-product-slider-2866.sp-wps-theme_one .wps-product-image { border: 0px none #dddddd;}#wps-slider-section #sp-woo-product-slider-2866.sp-wps-theme_one .wpsf-product:hover .wps-product-image, #sp-woo-product-slider-2866.sp-wps-custom-template .sp-wps-product-image-area:hover .wps-product-image .wpsf-product-img { border-color: #dddddd;}#wps-slider-section #sp-woo-product-slider-2866 .wps-pagination ul li .page-numbers {background: transparent; color: #5e5e5e; border: 2px solid #dddddd; } #wps-slider-section #sp-woo-product-slider-2866 .wps-pagination ul li .page-numbers:hover,#wps-slider-section #sp-woo-product-slider-2866 .wps-pagination ul li .page-numbers.current {background: #5e5e5e; color: #ffffff; border-color: #5e5e5e; }#wps-slider-section #sp-woo-product-slider-2866 a.sp-wqv-view-button{ display: none; }#wps-slider-section #sp-woo-product-slider-2866.sp-wps-custom-template .wpsf-product .wps-product-data { border: 0px none #c29a31;}#wps-slider-section #sp-woo-product-slider-2866.sp-wps-custom-template .wpsf-product:hover {border-color: #c29a31;}#wps-slider-section #sp-woo-product-slider-2866.sp-wps-custom-template .wpsf-product .sp-wps-product-details {padding: 10px 0px 10px 0px;}jQuery(document).ready(function($){ if (window.wps_slider_js) { window.wps_slider_js.params.loopFillGroupWithBlank = true; window.wps_slider_js.update(); }});<\/style><div id=\"wps-slider-section\" class=\"wps-slider-section wps-slider-section-2866\">\n\t\t<div class=\"wps-preloader\" id=\"wps-preloader-2866\" style=\"\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jolie-pharma.com\/wp-content\/plugins\/woo-product-slider\/src\/Admin\/assets\/images\/spinner.svg\" alt=\"loader-image\"\/>\n\t<\/div>\n\t\t\t<div id=\"sp-woo-product-slider-2866\" class=\"wps-product-section sp-wps-custom-template\" data-swiper='{ \"pauseOnHover\": true, \"infinite\": true, \"slidesToShow\": 6, \"speed\": 500,\"spaceBetween\": 20, \"autoplay\": true, \"autoplaySpeed\": 2000, \"swipe\": true, \"draggable\": true,\"freeMode\":false,\"carousel_accessibility\": false,\"mousewheel\": false,\"adaptiveHeight\": false, \"slidesPerView\":{\"lg_desktop\":6, \"desktop\":6, \"tablet\":4, \"mobile\":2} }'  dir=\"rtl\" data-preloader=\"1\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/after-sun-soothing-gel\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-150x150.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-150x150.jpg 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-300x300.jpg 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-768x768.jpg 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-12x12.jpg 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-600x600.jpg 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit-100x100.jpg 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_2fitlt2fitlt2fit.jpg 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/after-sun-soothing-gel\/\">After Sun Soothing Gel<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>279<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP279.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>195<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP195.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=6672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_6672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"6672\" data-product_sku=\"M00000127\" aria-label=\"Add to cart: &ldquo;After Sun Soothing Gel&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;After Sun Soothing Gel&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_6672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/emopair-leave-in-hair-cream\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-150x150.webp\" class=\"wpsf-product-img wp-post-image\" alt=\"Emopair Leave-In Hair Cream\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-150x150.webp 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-300x300.webp 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-1024x1024.webp 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-768x768.webp 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-12x12.webp 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-600x600.webp 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1-100x100.webp 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2026\/03\/emopair-1.webp 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/emopair-leave-in-hair-cream\/\">Emopair Leave-In Hair Cream<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>325<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP325.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>195<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP195.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=5107\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5107\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"5107\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Emopair Leave-In Hair Cream&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Emopair Leave-In Hair Cream&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5107\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/clean-shield-duo\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/clean-shield-duo\/\">Clean &#038; Shield Duo Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>850<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP850.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>425<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP425.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3725\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3725\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3725\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Clean &amp; Shield Duo Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Clean &amp; Shield Duo Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3725\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/total-glow-bundle\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/total-glow-bundle\/\">The Total Glow Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>2,550<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP2,550.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,275<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP1,275.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3723\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3723\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3723\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Total Glow Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Total Glow Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3723\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/morning-shield-set\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/morning-shield-set\/\">Morning Shield Set Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,775<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,775.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>888<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP888.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3721\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3721\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3721\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Morning Shield Set Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Morning Shield Set Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3721\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/glow-boost-trio\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/glow-boost-trio\/\">Glow Boost Trio Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,775<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,775.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>889<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP889.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3719\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3719\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3719\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Glow Boost Trio Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Glow Boost Trio Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3719\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/wake-up-glow-set\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/wake-up-glow-set\/\">The Complete Wake Up Glow Set<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,275<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,275.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>638<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP638.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3717\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3717\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3717\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Complete Wake Up Glow Set&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Complete Wake Up Glow Set&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3717\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/the-ultimate-hair-routine\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"tresor jolie pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/the-ultimate-hair-routine\/\">The Ultimate Hair Routine Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>2,080<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP2,080.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,040<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP1,040.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3715\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3715\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3715\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Ultimate Hair Routine Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Ultimate Hair Routine Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3715\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/hair-revival-set\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"tresor jolie pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/hair-revival-set\/\">The Hair Revival Set<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,525<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,525.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>765<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP765.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3711\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3711\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3711\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Hair Revival Set&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Hair Revival Set&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3711\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-whitening-deodorant-roll-on-50ml\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"Tr\u00e9sor Expert chamomile deodorant with whitening, moisturizing, antibacterial benefits\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-chamomile-deodorant-4in1-egypt.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-whitening-deodorant-roll-on-50ml\/\">Tresor Whitening Deodorant Roll-On &#8211; 50ml<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>275<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP275.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>165<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP165.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-whitening-deodorant-roll-on-50ml\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3353\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"3353\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Tresor Whitening Deodorant Roll-On - 50ml&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3353\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/grand-clear-anti-dandruff-shampoo-250ml\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"Grand Clear anti-dandruff shampoo with Piroctone Olamine and Zinc Pyrithione\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/grand-clear-anti-dandruff-shampoo-egypt.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/grand-clear-anti-dandruff-shampoo-250ml\/\">Grand Clear Anti-Dandruff Shampoo \u2013 250ml<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>555<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP555.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>289<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP289.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3351\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3351\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3351\" data-product_sku=\"M00000039\" aria-label=\"Add to cart: &ldquo;Grand Clear Anti-Dandruff Shampoo \u2013 250ml&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Grand Clear Anti-Dandruff Shampoo \u2013 250ml&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3351\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-expert-facial-cleanser-150ml-silicone-brush\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"Tr\u00e9sor Expert facial cleanser with Vitamin C, Niacinamide, and Glucosyl Hesperidin\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-vitamin-c-facial-cleanser-egypt.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-expert-facial-cleanser-150ml-silicone-brush\/\">Tresor Expert Facial Cleanser \u2013 150ml + Silicone Brush<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>350<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP350.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>195<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP195.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3349\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3349\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3349\" data-product_sku=\"M00000037\" aria-label=\"Add to cart: &ldquo;Tresor Expert Facial Cleanser \u2013 150ml + Silicone Brush&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Tresor Expert Facial Cleanser \u2013 150ml + Silicone Brush&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3349\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-expert-hair-lotion-250ml\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"Tr\u00e9sor Expert nourishing hair lotion with caffeine, biotin, and procapil\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-anti-hair-loss-lotion-egypt.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-expert-hair-lotion-250ml\/\">Tresor Expert Hair Lotion \u2013 250ml<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>800<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP800.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>469<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP469.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3347\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3347\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3347\" data-product_sku=\"M00000036\" aria-label=\"Add to cart: &ldquo;Tresor Expert Hair Lotion \u2013 250ml&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Tresor Expert Hair Lotion \u2013 250ml&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3347\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-expert-shampoo-250ml\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"Tr\u00e9sor Expert revitalizing shampoo and conditioner with caffeine and keratin\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/tresor-expert-revitalizing-shampoo-conditioner-egypt.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/tresor-expert-shampoo-250ml\/\">Tresor Expert Shampoo &#038; Conditioner \u2013 250ml<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>400<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP400.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>240<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP240.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3345\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3345\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3345\" data-product_sku=\"M00000038\" aria-label=\"Add to cart: &ldquo;Tresor Expert Shampoo &amp; Conditioner \u2013 250ml&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Tresor Expert Shampoo &amp; Conditioner \u2013 250ml&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3345\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/sunscreen-spf-50-for-kids\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/KIDS-SUNSCREEN.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/sunscreen-spf-50-for-kids\/\">Sunscreen SPF 50+ for Kids<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>500<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP500.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>225<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP225.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=2727\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2727\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"2727\" data-product_sku=\"M00000114\" aria-label=\"Add to cart: &ldquo;Sunscreen SPF 50+ for Kids&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Sunscreen SPF 50+ for Kids&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2727\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/sunscreen-spf-50-for-face\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"Non-greasy sunscreen spray SPF 50 with antioxidants and UV protection\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/j-skin-hacks-sunscreen-spray-spf50-egypt.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/sunscreen-spf-50-for-face\/\">Sunscreen SPF 50+ for Adults<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>500<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP500.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>225<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP225.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=2726\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2726\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"2726\" data-product_sku=\"M00000113\" aria-label=\"Add to cart: &ldquo;Sunscreen SPF 50+ for Adults&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Sunscreen SPF 50+ for Adults&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2726\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n\t\t\t<\/div> <!-- end swiper-wrapper tag  -->\n\t\t\t\t\t\t\t\t<!-- pagination dots -->\n\t\t\t<div class=\"wpsp-pagination-dot swiper-pagination\"><\/div>\n\t\t\t<!-- !pagination dots -->\n\t\t\t\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-97464fe5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 500; display: inline-block; letter-spacing: -2.0px;\">\n    SHOP \ud83d\udecd\ufe0f\n  <\/span><br>\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 25px; font-weight: 100; display: inline-block; letter-spacing: -2.0px;\">\n    BY CATEGORY\n<\/div>\n\n\n\n<div class=\"linked-carousel\">\n  <div class=\"carousel-item\">\n    <a href=\"https:\/\/jolie-pharma.com\/product-category\/skin-care\/\" target=\"_blank\"><\/a>\n    <img decoding=\"async\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/SKINCARE.png\" alt=\"Skincare\">\n  <\/div>\n  <div class=\"carousel-item\">\n    <a href=\"https:\/\/jolie-pharma.com\/product-category\/hair-care\/\"><\/a>\n    <img decoding=\"async\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/HAIRCARE.png\" alt=\"Haircare\">\n  <\/div>\n  <div class=\"carousel-item\">\n    <a href=\"https:\/\/jolie-pharma.com\/product-category\/bundles\/\"><\/a>\n    <img decoding=\"async\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/BUNDLES-MODEL.png\" alt=\"Bundles\">\n  <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-edd1f1ee\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-55f47113 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/jolie-pharma.com\/shop\/\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">Shop Here<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M112 112C112 50.14 162.1 0 224 0C285.9 0 336 50.14 336 112V160H400C426.5 160 448 181.5 448 208V416C448 469 405 512 352 512H96C42.98 512 0 469 0 416V208C0 181.5 21.49 160 48 160H112V112zM160 160H288V112C288 76.65 259.3 48 224 48C188.7 48 160 76.65 160 112V160zM136 256C149.3 256 160 245.3 160 232C160 218.7 149.3 208 136 208C122.7 208 112 218.7 112 232C112 245.3 122.7 256 136 256zM312 208C298.7 208 288 218.7 288 232C288 245.3 298.7 256 312 256C325.3 256 336 245.3 336 232C336 218.7 325.3 208 312 208z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-251f2f5a\"><div class=\"uagb-separator-spacing-wrapper\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-layout-grid uagb-block-d4848b69 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 500; display: inline-block; letter-spacing: -2.0px;\">\n    OFFERS\n  <\/span><br>\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 25px; font-weight: 100; display: inline-block; letter-spacing: -2.0px;\">\n    &#038; BUNDLES <span style=\"color: #FFD700;\">\ud83c\udf81<\/span>\n  <\/span>\n<\/div>\n\n\n<style id=\"sp_product_slider_dynamic_css3044\">#wps-slider-section #sp-woo-product-slider-3044.wps-product-section .wpsp-pagination-dot .swiper-pagination-bullet{ background-color:#cccccc; } #wps-slider-section #sp-woo-product-slider-3044.wps-product-section .wpsp-pagination-dot .swiper-pagination-bullet.swiper-pagination-bullet-active{ background-color:#333333; }@media (max-width: 480px) {#wps-slider-section #sp-woo-product-slider-3044.wps-product-section .wpsp-pagination-dot { display:none;}}#wps-slider-section #sp-woo-product-slider-3044.wps-product-section[data-layout=grid] { margin-left: -20px;}#wps-slider-section #sp-woo-product-slider-3044 .wpsf-grid-item { padding-left: 20px; margin-bottom: 20px;}#wps-slider-section #sp-woo-product-slider-3044 .wpsf-product-title a{ color: #444444; font-size: 15px; } #wps-slider-section #sp-woo-product-slider-3044 .wpsf-product-title a:hover{ color: #955b89; }#wps-slider-section #sp-woo-product-slider-3044 .wpsf-product-price { color: #222222; font-size: 14px; } #wps-slider-section #sp-woo-product-slider-3044 .wpsf-product-price del span { color: #888888; }#wps-slider-section #sp-woo-product-slider-3044 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button){ color: #ffffff; background-color: #c29a31; border: 0px solid #ffffff; } #wps-slider-section #sp-woo-product-slider-3044 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button):hover, #wps-slider-section #sp-woo-product-slider-3044 .wpsf-cart-button a.added_to_cart{ color: #000000; background-color: #ffffff; border-color: #ffffff; }#sp-woo-product-slider-3044.sp-wps-custom-template .wps-product-image .wpsf-product-img,#sp-woo-product-slider-3044.sp-wps-theme_one .wps-product-image { border: 0px none #dddddd;}#wps-slider-section #sp-woo-product-slider-3044.sp-wps-theme_one .wpsf-product:hover .wps-product-image, #sp-woo-product-slider-3044.sp-wps-custom-template .sp-wps-product-image-area:hover .wps-product-image .wpsf-product-img { border-color: #dddddd;}#wps-slider-section #sp-woo-product-slider-3044 .wps-pagination ul li .page-numbers {background: transparent; color: #5e5e5e; border: 2px solid #dddddd; } #wps-slider-section #sp-woo-product-slider-3044 .wps-pagination ul li .page-numbers:hover,#wps-slider-section #sp-woo-product-slider-3044 .wps-pagination ul li .page-numbers.current {background: #5e5e5e; color: #ffffff; border-color: #5e5e5e; }#wps-slider-section #sp-woo-product-slider-3044 a.sp-wqv-view-button{ display: none; }#wps-slider-section #sp-woo-product-slider-3044.sp-wps-custom-template .wpsf-product .wps-product-data { border: 0px none #c29a31;}#wps-slider-section #sp-woo-product-slider-3044.sp-wps-custom-template .wpsf-product:hover {border-color: #c29a31;}#wps-slider-section #sp-woo-product-slider-3044.sp-wps-custom-template .wpsf-product .sp-wps-product-details {padding: 10px 0px 10px 0px;}jQuery(document).ready(function($){ if (window.wps_slider_js) { window.wps_slider_js.params.loopFillGroupWithBlank = true; window.wps_slider_js.update(); }});<\/style><div id=\"wps-slider-section\" class=\"wps-slider-section wps-slider-section-3044\">\n\t\t<div class=\"wps-preloader\" id=\"wps-preloader-3044\" style=\"\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jolie-pharma.com\/wp-content\/plugins\/woo-product-slider\/src\/Admin\/assets\/images\/spinner.svg\" alt=\"loader-image\"\/>\n\t<\/div>\n\t\t\t<div id=\"sp-woo-product-slider-3044\" class=\"wps-product-section sp-wps-custom-template\" data-swiper='{ \"pauseOnHover\": true, \"infinite\": true, \"slidesToShow\": 6, \"speed\": 500,\"spaceBetween\": 20, \"autoplay\": true, \"autoplaySpeed\": 2000, \"swipe\": true, \"draggable\": true,\"freeMode\":false,\"carousel_accessibility\": false,\"mousewheel\": false,\"adaptiveHeight\": false, \"slidesPerView\":{\"lg_desktop\":6, \"desktop\":6, \"tablet\":4, \"mobile\":2} }'  dir=\"rtl\" data-preloader=\"1\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/clean-shield-duo\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/6.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/clean-shield-duo\/\">Clean &#038; Shield Duo Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>850<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP850.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>425<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP425.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3725\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3725\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3725\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Clean &amp; Shield Duo Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Clean &amp; Shield Duo Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3725\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/total-glow-bundle\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/8.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/total-glow-bundle\/\">The Total Glow Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>2,550<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP2,550.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,275<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP1,275.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3723\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3723\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3723\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Total Glow Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Total Glow Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3723\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/morning-shield-set\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/4.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/morning-shield-set\/\">Morning Shield Set Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,775<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,775.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>888<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP888.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3721\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3721\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3721\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Morning Shield Set Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Morning Shield Set Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3721\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/glow-boost-trio\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/5.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/glow-boost-trio\/\">Glow Boost Trio Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,775<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,775.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>889<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP889.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3719\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3719\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3719\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Glow Boost Trio Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Glow Boost Trio Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3719\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/wake-up-glow-set\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"JSKIN HACKS Jolie Pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/7.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/wake-up-glow-set\/\">The Complete Wake Up Glow Set<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,275<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,275.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>638<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP638.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3717\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3717\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3717\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Complete Wake Up Glow Set&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Complete Wake Up Glow Set&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3717\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/the-ultimate-hair-routine\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"tresor jolie pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/1.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/the-ultimate-hair-routine\/\">The Ultimate Hair Routine Bundle<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>2,080<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP2,080.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,040<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP1,040.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3715\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3715\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3715\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Ultimate Hair Routine Bundle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Ultimate Hair Routine Bundle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3715\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n \n<div class=\"wpsf-product  swiper-slide\">\n<div class=\"wps-product-data\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/jolie-pharma.com\/en\/product\/hair-revival-set\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-150x150.png\" class=\"wpsf-product-img wp-post-image\" alt=\"tresor jolie pharma\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-150x150.png 150w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-300x300.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-1024x1024.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-768x768.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-1536x1536.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-12x12.png 12w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-600x600.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2-100x100.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/2.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n\t<div class=\"sp-wps-product-details\">\n\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/jolie-pharma.com\/en\/product\/hair-revival-set\/\">The Hair Revival Set<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>1,525<\/span><\/del> <span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a \u0647\u0648: EGP1,525.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">EGP<\/span>765<\/span><\/ins><span class=\"screen-reader-text\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: EGP765.<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/842?add-to-cart=3711\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3711\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"3711\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;The Hair Revival Set&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;The Hair Revival Set&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3711\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t<\/div> <!--  sp-wps-product-details. -->\n\n\t\t<\/div> <!-- wps-product-data. -->\n<\/div> <!-- wpsf-product. -->\n\t\t\t<\/div> <!-- end swiper-wrapper tag  -->\n\t\t\t\t\t\t\t\t<!-- pagination dots -->\n\t\t\t<div class=\"wpsp-pagination-dot swiper-pagination\"><\/div>\n\t\t\t<!-- !pagination dots -->\n\t\t\t\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer uag-hide-desktop uag-hide-tab\"><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-52f8655e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1-819x1024.png\" alt=\"\" class=\"has-border-color has-ast-global-color-0-border-color wp-image-3381\" style=\"border-width:1px;border-radius:16px;box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1-819x1024.png 819w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1-240x300.png 240w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1-768x960.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1-10x12.png 10w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1-600x750.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/GOLD-1.png 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-mob uagb-block-53f1150b alignwide uagb-is-root-container\">\n<figure class=\"wp-block-image size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"800\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD.png\" alt=\"\" class=\"has-border-color has-ast-global-color-0-border-color wp-image-2943\" style=\"border-width:1px;border-radius:30px;box-shadow:var(--wp--preset--shadow--natural);object-fit:contain\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD.png 1920w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD-300x125.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD-1024x427.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD-768x320.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD-1536x640.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD-18x8.png 18w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/GOLD-600x250.png 600w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-15edea75 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-108af272\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 20px; font-weight: 100; display: inline-block; letter-spacing: -1.0px; color: #454f5e;\">\n    Follow Us On\n  <\/span>\n  \n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 600; display: inline-block; letter-spacing: -3.0px; color: #454f5e;\">\n    Social Media \ud83d\udcf8\n  <\/span>\n<\/div>\n\n\n\n<div data-aos= \"fade-right\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-layout-flex uagb-block-abb5e97c\">\n<div class=\"instagram-carousel-wrapper\">\n  <div class=\"instagram-carousel-slide\">\n    <!-- New Embed 1 -->\n    <blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DOizDuGiJI_\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n      <!-- full embed content for video 1 -->\n    <\/blockquote>\n  <\/div>\n\n  <div class=\"instagram-carousel-slide\">\n    <!-- New Embed 2 -->\n    <blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DSH6B60kgPn\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n      <!-- full embed content for video 2 -->\n    <\/blockquote>\n  <\/div>\n\n  <div class=\"instagram-carousel-slide\">\n    <!-- New Embed 3 -->\n    <blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DTN593RiapB\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n      <!-- full embed content for video 3 -->\n    <\/blockquote>\n  <\/div>\n\n  <div class=\"instagram-carousel-slide\">\n    <!-- New Embed 4 -->\n    <blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DTtAY7mFZxl\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n      <!-- full embed content for video 4 -->\n    <\/blockquote>\n  <\/div>\n<\/div>\n\n<!-- Instagram Embed Script -->\n<script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n<\/div>\n<\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-d1d2daa3\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 20px; font-weight: 100; display: inline-block; letter-spacing: -1.0px; color: #454f5e;\">\n    OUR\n  <\/span>\n  \n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 600; display: inline-block; letter-spacing: -3.0px; color: #454f5e;\">\n    BRANDS \n  <\/span>\n<\/div>\n<\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-layout-flex uagb-block-e0e2b0e2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-e2defe74\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"margin-top:0rem;margin-right:0px;margin-bottom:0rem;margin-left:0px\"><a href=\"https:\/\/jolie-pharma.com\/brand\/jskin-hacks\/\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"98\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/J-SKIN-LOGO-120px.png\" alt=\"\" class=\"wp-image-2922\" style=\"object-fit:contain;width:120px;height:120px\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/J-SKIN-LOGO-120px.png 120w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/J-SKIN-LOGO-120px-15x12.png 15w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-77edfd41\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"margin-right:0px;margin-left:0px\"><a href=\"https:\/\/jolie-pharma.com\/brand\/tresor\/\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/TRESOR-logo-130px-edited.png\" alt=\"\" class=\"wp-image-3399\" style=\"object-fit:contain;width:120px;height:120px\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/TRESOR-logo-130px-edited.png 100w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/TRESOR-logo-130px-edited-12x12.png 12w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-0c4c272f\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-26cc7bdb wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/jolie-pharma.com\/shop\/\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">Shop Here<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M112 112C112 50.14 162.1 0 224 0C285.9 0 336 50.14 336 112V160H400C426.5 160 448 181.5 448 208V416C448 469 405 512 352 512H96C42.98 512 0 469 0 416V208C0 181.5 21.49 160 48 160H112V112zM160 160H288V112C288 76.65 259.3 48 224 48C188.7 48 160 76.65 160 112V160zM136 256C149.3 256 160 245.3 160 232C160 218.7 149.3 208 136 208C122.7 208 112 218.7 112 232C112 245.3 122.7 256 136 256zM312 208C298.7 208 288 218.7 288 232C288 245.3 298.7 256 312 256C325.3 256 336 245.3 336 232C336 218.7 325.3 208 312 208z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-mob uagb-block-f4d0da74 alignwide uagb-is-root-container\">\n<figure class=\"wp-block-image size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"800\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE.png\" alt=\"\" class=\"has-border-color has-ast-global-color-0-border-color wp-image-2944\" style=\"border-width:1px;border-radius:30px;box-shadow:var(--wp--preset--shadow--natural);object-fit:contain\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE.png 1920w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE-300x125.png 300w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE-1024x427.png 1024w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE-768x320.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE-1536x640.png 1536w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE-18x8.png 18w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/07\/WHITE-600x250.png 600w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-4ff55865 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2-819x1024.png\" alt=\"\" class=\"has-border-color has-ast-global-color-0-border-color wp-image-3411\" style=\"border-width:1px;border-radius:16px;box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2-819x1024.png 819w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2-240x300.png 240w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2-768x960.png 768w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2-10x12.png 10w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2-600x750.png 600w, https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/08\/Artboard-1-copy-2.png 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-9a76f6ea alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div style=\"text-align: center; line-height: 1.1;\">\n  <span style=\"font-family: Montserrat, sans-serif; font-size: 20px; font-weight: 100; display: inline-block; letter-spacing: -1.0px; color: #454f5e;\">\n    What Our \n  <\/span>\n  \n  <span style=\"font-family: Montserrat, sans-serif; font-size: 36px; font-weight: 600; display: inline-block; letter-spacing: -3.0px; color: #454f5e;\">\n    Customers Say \ud83d\udd0a\n  <\/span>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-testimonial uagb-slick-carousel uagb-tm__arrow-outside uagb-block-e17f940b\"><div class=\"is-carousel uagb-tm__columns-1 uagb-tm__items\"><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-color \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\"><strong>&#8220;Mafish hype, el whitening cream beyshteghal bdon mawaly.&#8221;<br><\/strong>\u00a0E7sas el skin ba3do mo7taram, mesh be7rok aw yshdd. Lazem te3rafo t3melo eh el brand dah!<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\"><br>\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><span class=\"uagb-tm__company\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-color \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\"><strong>&#8220;El eye cream rayya7 3eni ba3d el shoghl w el sahar.&#8221;<br><\/strong>\u00a0Bsta5dmo sob7 w leil\u2026 el puffiness ba2a a2al b kteer, w shakli ba2a as7a.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\"><br>\u2b50\u2b50\u2b50\u2b50\u2b50 <\/span><span class=\"uagb-tm__company\">Company Name<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-color \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\"><strong>&#8220;Ana honestly kont mesh motashaweka awi\u2026 bs el serum literally khalani addicted.&#8221;<br><\/strong>\u00a0Bayeban el far2 men awel mara, mesh greasy w el skin betet7asan kol youm.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\"><br>\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><span class=\"uagb-tm__company\">Company Name<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-color \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\"><strong>&#8220;Ana usually mesh bktb reviews\u2026 bs el difference worth sharing.&#8221;<br><\/strong>\u00a0Used them 3 weeks, w 7ata el nas 7asto bel far2. Kol yom ba2a fi glow sa7i.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\"><br>\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><span class=\"uagb-tm__company\">Company Name<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-color \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\"><strong>&#8220;Talama fe brands Egyptian kda, malhash lazma el imported.&#8221;<br><\/strong>\u00a0El quality, el design, el result, kollo excellent. Mesh fake at all<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\"><br>\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><span class=\"uagb-tm__company\">Company Name<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-ad0a5045 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b8b8b421\">\n<div class=\"wp-block-uagb-info-box uagb-block-75e13b78 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Have a question?<\/h2><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-35325fb5\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-a6aee5e8 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/jolie-pharma.com\/contact-us\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">get in touch<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5d07c623\">\n<div class=\"wp-block-uagb-info-box uagb-block-4e148387 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Track Your Order<\/h5><\/div><p class=\"uagb-ifb-desc\">Wondering where your order is? Track it here and stay updated every step of the way.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/egyptpost.gov.eg\/ar-eg\/home\/eservices\/track-and-trace\/\" target=\"_self\" onclick=\"return true;\" class=\"uagb-infobox-cta-link\" rel=\"noopener noreferrer\"><span class=\"uagb-inline-editing\">Track your Order<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M112 112C112 50.14 162.1 0 224 0C285.9 0 336 50.14 336 112V160H400C426.5 160 448 181.5 448 208V416C448 469 405 512 352 512H96C42.98 512 0 469 0 416V208C0 181.5 21.49 160 48 160H112V112zM160 160H288V112C288 76.65 259.3 48 224 48C188.7 48 160 76.65 160 112V160zM136 256C149.3 256 160 245.3 160 232C160 218.7 149.3 208 136 208C122.7 208 112 218.7 112 232C112 245.3 122.7 256 136 256zM312 208C298.7 208 288 218.7 288 232C288 245.3 298.7 256 312 256C325.3 256 336 245.3 336 232C336 218.7 325.3 208 312 208z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f326328f\">\n<div class=\"wp-block-uagb-info-box uagb-block-ed1e0952 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Return &amp; Refund\u200b<\/h5><\/div><p class=\"uagb-ifb-desc\">Not satisfied with your purchase? Review our return policy and request a refund with ease.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/jolie-pharma.com\/refund_returns\/\" target=\"_blank\" onclick=\"return true;\" class=\"uagb-infobox-cta-link\" rel=\"noopener noreferrer\"><span class=\"uagb-inline-editing\">Read More<\/span><\/a><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-1f7ac485\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-10621cb3 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/jolie-pharma.com\/shop\/\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">Shop Here<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M112 112C112 50.14 162.1 0 224 0C285.9 0 336 50.14 336 112V160H400C426.5 160 448 181.5 448 208V416C448 469 405 512 352 512H96C42.98 512 0 469 0 416V208C0 181.5 21.49 160 48 160H112V112zM160 160H288V112C288 76.65 259.3 48 224 48C188.7 48 160 76.65 160 112V160zM136 256C149.3 256 160 245.3 160 232C160 218.7 149.3 208 136 208C122.7 208 112 218.7 112 232C112 245.3 122.7 256 136 256zM312 208C298.7 208 288 218.7 288 232C288 245.3 298.7 256 312 256C325.3 256 336 245.3 336 232C336 218.7 325.3 208 312 208z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POWERED BY \u2b50 102 YEARS OF EXPERIENCE \u2b50 POWERED BY \u2b50 102 YEARS OF EXPERIENCE \u2b50 TRENDING PRODUCTS \ud83d\udd25 SHOP \ud83d\udecd\ufe0f BY CATEGORY OFFERS &#038; BUNDLES \ud83c\udf81 Follow Us On Social Media \ud83d\udcf8 OUR BRANDS What Our Customers Say \ud83d\udd0a<\/p>\n","protected":false},"author":1,"featured_media":3798,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-842","page","type-page","status-publish","has-post-thumbnail","hentry","desktop-align-center","tablet-align-left","mobile-align-center"],"uagb_featured_image_src":{"full":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false],"thumbnail":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low-150x150.png",150,150,true],"medium":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low-300x276.png",300,276,true],"medium_large":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false],"large":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false],"1536x1536":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false],"2048x2048":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false],"trp-custom-language-flag":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low-13x12.png",13,12,true],"woocommerce_thumbnail":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low-300x300.png",300,300,true],"woocommerce_single":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false],"woocommerce_gallery_thumbnail":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low-100x100.png",100,100,true],"quick_view_image_size":["https:\/\/jolie-pharma.com\/wp-content\/uploads\/2025\/11\/Jolie-Pharma-Featured-Image-compress-low.png",400,368,false]},"uagb_author_info":{"display_name":"Mohamed Wagih","author_link":"https:\/\/jolie-pharma.com\/en\/author\/mohamed-wagihoutlook-com\/"},"uagb_comment_info":0,"uagb_excerpt":"POWERED BY \u2b50 102 YEARS OF EXPERIENCE \u2b50 POWERED BY \u2b50 102 YEARS OF EXPERIENCE \u2b50 TRENDING PRODUCTS \ud83d\udd25 SHOP \ud83d\udecd\ufe0f BY CATEGORY OFFERS &#038; BUNDLES \ud83c\udf81 Follow Us On Social Media \ud83d\udcf8 OUR BRANDS What Our Customers Say \ud83d\udd0a","_links":{"self":[{"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/pages\/842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/comments?post=842"}],"version-history":[{"count":259,"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/pages\/842\/revisions"}],"predecessor-version":[{"id":5112,"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/pages\/842\/revisions\/5112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/media\/3798"}],"wp:attachment":[{"href":"https:\/\/jolie-pharma.com\/en\/wp-json\/wp\/v2\/media?parent=842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}